{"id":16798,"date":"2026-07-02T19:30:23","date_gmt":"2026-07-02T17:30:23","guid":{"rendered":"http:\/\/liseandco-creations.com\/?post_type=product&#038;p=16798"},"modified":"2026-07-02T19:30:52","modified_gmt":"2026-07-02T17:30:52","slug":"etui-a-lunettes-54","status":"publish","type":"product","link":"https:\/\/liseandco-creations.com\/index.php\/produit\/etui-a-lunettes-54\/","title":{"rendered":"Etui \u00e0 lunettes"},"content":{"rendered":"<p>\u2665 Cousu main \u2665<\/p>\n<p>\ud83c\udf38 Tissu import\u00e9 du Japon \ud83c\udf38<\/p>\n<p><strong>Mati\u00e8re <\/strong><\/p>\n<p>-Ext\u00e9rieur : tissu coton<\/p>\n<p>-Int\u00e9rieur : simili-cuir<\/p>\n<p><strong>Dimensions <\/strong><\/p>\n<p>-9 x 18 cms<\/p>\n<p><strong>* Id\u00e9al pour ranger vos lunettes de vue ou de soleil ! *<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cet \u00e9l\u00e9gant \u00e9tui en tissu vous permet de ranger et prot\u00e9ger vos lunettes de soleil ou m\u00eame vos lunettes de vue, tout en affichant votre style et personnalit\u00e9 !<\/p>\n<p>L\u00e9ger et peu encombrant il pourra \u00eatre gliss\u00e9 dans une poche de v\u00eatement ou un petit sac \u00e0 main. On peut aussi y accrocher une lani\u00e8re gr\u00e2ce \u00e0 une astucieuse petite anse sur le cot\u00e9 du fermoir.<\/p>\n<p>Cet \u00e9tui peut \u00e9galement servir de trousse \u00e0 crayons ou feutres .<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":16799,"comment_status":"open","ping_status":"closed","template":"","meta":{"_links_to":"","_links_to_target":""},"_links":{"self":[{"href":"https:\/\/liseandco-creations.com\/index.php\/wp-json\/wp\/v2\/product\/16798"}],"collection":[{"href":"https:\/\/liseandco-creations.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/liseandco-creations.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/liseandco-creations.com\/index.php\/wp-json\/wp\/v2\/comments?post=16798"}],"version-history":[{"count":1,"href":"https:\/\/liseandco-creations.com\/index.php\/wp-json\/wp\/v2\/product\/16798\/revisions"}],"predecessor-version":[{"id":16800,"href":"https:\/\/liseandco-creations.com\/index.php\/wp-json\/wp\/v2\/product\/16798\/revisions\/16800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/liseandco-creations.com\/index.php\/wp-json\/wp\/v2\/media\/16799"}],"wp:attachment":[{"href":"https:\/\/liseandco-creations.com\/index.php\/wp-json\/wp\/v2\/media?parent=16798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}